{"id":2793,"date":"2021-04-17T22:05:13","date_gmt":"2021-04-17T22:05:13","guid":{"rendered":"https:\/\/canaguaro.cinefagos.net\/n02\/?p=2793"},"modified":"2021-04-19T22:03:09","modified_gmt":"2021-04-19T22:03:09","slug":"entrevista-julio-luzardo","status":"publish","type":"post","link":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/","title":{"rendered":"Entrevista a Julio Luzardo"},"content":{"rendered":"\r\n<p class=\"autor wp-block-paragraph\">Oswaldo Osorio<\/p>\r\n\r\n\r\n\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"22\" height=\"8\" class=\"wp-image-2693\" src=\"http:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/sep.png\" alt=\"\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<p class=\"entradilla wp-block-paragraph\">El verdadero cine cl\u00e1sico colombiano comenz\u00f3 en los a\u00f1os sesenta con los filmes de Julio Luzardo y Jos\u00e9 Mar\u00eda Arzuaga. Antes de ellos, solo hay pel\u00edculas viejas. Y son cl\u00e1sicos por la gran influencia que ejercieron en los futuros cineastas del pa\u00eds y porque a\u00fan hasta ahora, con sus limitaciones t\u00e9cnicas y todo, mantienen su fuerza y su vigencia. Siendo Arzuaga espa\u00f1ol, Luzardo se erige, entonces, como nuestro cl\u00e1sico nacional. Y lo es solo con dos pel\u00edculas (o tres t\u00edtulos, para ser m\u00e1s exactos, porque de <em>3 cuentos colombianos <\/em>dirigi\u00f3 solo dos).\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">En el breve recorrido que este di\u00e1logo hace por su carrera, Julio Luzardo mira con nostalgia y sentido cr\u00edtico, pero tambi\u00e9n con un poco de amargura, su paso por un medio por el que le toc\u00f3 trasegar en una \u00e9poca nada favorable para el cine y el oficio que quer\u00eda ejercer. \u00a0\u00a0<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfC\u00f3mo fue ese salto de haberse formado en la UCLA (Universidad de California en Los Angeles) y en el ambiente de Hollywood para venir a Colombia a hacer cine con todas las limitaciones que ten\u00eda este pa\u00eds en su cinematograf\u00eda?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">El cine en general, si a uno le gusta, es muy f\u00e1cil, el cine no es un gran misterio. Casi cualquier persona puede hacer cine, pero es que, en esa \u00e9poca, en los a\u00f1os sesenta, no exist\u00eda nada. Solo hab\u00eda unos laboratorios muy precarios. Yo llegu\u00e9 en una \u00e9poca cuando el sonido no es como ahora lo conocemos, que empez\u00f3 con la Nagra, que fue lo que permiti\u00f3 que hici\u00e9ramos sonido directo sin problemas. Hasta ese momento, el sonido hab\u00eda sido un desastre y est\u00e1bamos en Colombia muy atrasados, empezamos doce a\u00f1os despu\u00e9s de Hollywood, y eso hasta cierto punto se mantuvo para los a\u00f1os sesenta.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Cuando yo llegu\u00e9 se trabajaba con la Arri 2c, era una c\u00e1mara muy fuerte y el sonido era inmundo, y por eso, hasta el a\u00f1o 1973, tuvimos que trabajar con doblaje, porque est\u00e1bamos tecnol\u00f3gicamente muy atrasados. En <em>El r\u00edo de las tumbas<\/em> (1964) no hab\u00eda script, porque yo me peli\u00e9 con la script, que era Dina Moscovici, porque me estaba medio boicoteando la pel\u00edcula. Y como no hab\u00eda sonido magn\u00e9tico, no hab\u00eda nada, solo hab\u00eda lo que yo iba anotando y despu\u00e9s los actores ten\u00edan que sincronizarlo todo en el doblaje.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Est\u00e1bamos en un pa\u00eds donde el cine b\u00e1sicamente no exist\u00eda, apenas hab\u00eda una cosa que se llamaba Cinematogr\u00e1fica Colombiana, que era casi como un edificio abandonado por ah\u00ed, con un poco de cuartos y unos salones donde se pod\u00eda hacer doblajes y otras cositas, y ten\u00eda una copiadora \u00f3ptica, era el \u00fanico sitio donde se pod\u00eda hacer eso. Todo era muy primario, \u00e9ramos absolutamente trabajando con las u\u00f1as por la falta de tecnolog\u00eda, adem\u00e1s de que no hab\u00eda apoyo del gobierno y no hab\u00eda plata.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfQu\u00e9 es lo que m\u00e1s destaca de esas primeras pel\u00edculas?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Una de las cosas que m\u00e1s destaco de <em>El r\u00edo de las tumbas<\/em> y de <em>3 cuentos colombianos<\/em> (1962) es que lo hicimos casi como si estuvi\u00e9ramos haciendo un trabajo en la universidad, porque tuve el lujo de tener unos buenos actores, aunque entre comillas, porque todos eran improvisados, o sea, ninguno hab\u00eda trabajado en una pel\u00edcula, ni Santiago Garc\u00eda, ni Carlos Duplat, ni Carlos Jos\u00e9 Perozo, ni Carlos Jos\u00e9 Reyes. Hab\u00eda otros que no eran actores y todos \u00e9ramos muy j\u00f3venes, el pap\u00e1 de todos era Santiago Garc\u00eda, que ya se hab\u00eda establecido un poco en el teatro con el B\u00faho, pero no hab\u00eda empezado todav\u00eda con La Candelaria, ni nada de eso.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfPara hacer estas pel\u00edculas la din\u00e1mica de rodaje la aprendi\u00f3 en la universidad?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">No dir\u00eda eso, porque en los dos primeros a\u00f1os no nos dejaban ver nada de cine, pero antes de entrar a la UCLA, s\u00ed est\u00e1bamos muy involucrados en el medio del teatro y del cine. Como yo ten\u00eda esa sed de hacer algo, antes de haber tomado el primer curso en la universidad hice mi primera pel\u00edcula. Es lo que te digo, que el cine es muy f\u00e1cil, es casi intuitivo, es algo como que le nace a uno y eso fue lo que me pas\u00f3 a m\u00ed, sobre todo por lo de mi pap\u00e1 metido con un teatro como el Aladino. Yo me entusiasm\u00e9 porque lo que m\u00e1s me gustaba en la vida era ver y hacer cine, entonces dije que iba a ser un director y empec\u00e9 a hacer cosas y termin\u00e9 en la universidad, pero la universidad no me ense\u00f1\u00f3 a hacer cine.<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p>&#8230; el cine es muy f\u00e1cil, es casi intuitivo, es algo como que le nace a uno y eso fue lo que me pas\u00f3 a m\u00ed, sobre todo por lo de mi pap\u00e1 metido con un teatro como el Aladino.<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfY el teatro, qu\u00e9 tanto aport\u00f3 al oficio?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Por eso el teatro me gusta mucho, porque el teatro te permit\u00eda no tener ese misticismo que le hab\u00edan creado al cine. Todos los pioneros del cine en Hollywood le met\u00edan mucho misterio, eso era como si fueran unos magos, entonces hacer cine para ellos era ser un mago. \u00a1Qu\u00e9 mago ni qu\u00e9 carajos! Lo que pasa es que ellos se quedaban callados y cuando sab\u00edan algo no se lo dec\u00edan a nadie m\u00e1s. Era un medio muy cerrado, lleno de sindicatos que no dejaban hacer nada. Si no ten\u00edas un estudio que te arreglara todo, no pod\u00edas hacer cine. En esa \u00e9poca no hab\u00eda casi cine independiente, porque los sindicatos absorb\u00edan absolutamente todo, y encima es que, si t\u00fa no eras jud\u00edo, entonces no entrabas a la industria, mucho menos si eras mexicano o latinoamericano.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfC\u00f3mo es que si su formaci\u00f3n y el medio en que se dio era el cine de Hollywood, cuando vino a Colombia hizo este tipo de cine, es decir, realista y de cr\u00edtica social y pol\u00edtica?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Porque de cierta forma era el m\u00e1s f\u00e1cil de hacer. Porque la f\u00f3rmula de Hollywood es el espect\u00e1culo, que es costoso. No pod\u00edamos imitar esa vaina. Entonces lo m\u00e1s f\u00e1cil era trabajar en el campo, con historias sencillas. A m\u00ed me llam\u00f3 mucho la atenci\u00f3n <em>Ra\u00edces<\/em>, de Benito Alazraki (1954), que era muy sencilla y tuvo mucho \u00e9xito. Y eso lo pod\u00edamos hacer con campesinos colombianos y no nos costaba mucha plata, porque plata no hab\u00eda. Yo intent\u00e9 conseguir financiaci\u00f3n y nada, era un callej\u00f3n sin salida. Hoy en d\u00eda llega el FDC y te regala 2500 millones y qu\u00e9 hace con eso, una mierda, b\u00e1sicamente. Yo nunca tuve ni cinco centavos del gobierno en toda mi vida profesional.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfPor qu\u00e9 hacer una pel\u00edcula sobre la Violencia <\/em>(El r\u00edo de las tumbas)<em>, aunque la mostrara entre l\u00edneas, justo en ese tiempo? \u00bfNo tuvo alguna presi\u00f3n o problemas de censura?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">A m\u00ed me interesaba mucho esa violencia, yo le\u00eda todo lo que pod\u00eda sobre las guerrillas del Llano y el problema entre conservadores y liberales. Cuando nosotros arrancamos la pel\u00edcula, ese mismo a\u00f1o se fundaron las FARC al otro lado del r\u00edo, en Marquetalia, est\u00e1bamos pegados. Aunque hist\u00f3ricamente nosotros no sab\u00edamos nada de eso. Pero no, yo nunca tuve ning\u00fan problema de censura.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Trabaj\u00f3 tambi\u00e9n en otros proyectos como guionista y fot\u00f3grafo\u2026<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Tengo dos casos solamente, <em>Un \u00e1ngel de la calle <\/em>(Zacar\u00edas G\u00f3mez Urquiza, 1967) y <em>Bajo la tierra <\/em>(Santiago Garc\u00eda, 1968). La primera fue un experimento que se hizo para formar una sociedad que pudiera tener proyecci\u00f3n, entonces llamaron a R\u00f3mulo Lara, que era de los millonarios de esa \u00e9poca y le interesaba el cine. La sociedad la reuni\u00f3 Lizardo D\u00edaz, que era Felipe de Los Tolimenses, y consigui\u00f3 tambi\u00e9n a Pel\u00edculas Mexicanas \u2013que eso fue un gran error\u2013 y otros que eran entusiastas de esto. \u00c9ramos como siete u ocho. Y se hizo esa pel\u00edcula sacada de una obra de radio teatro de Efra\u00edn Arce Arag\u00f3n, que era un melodramon\u00f3n tenaz, y a seis manos tratamos de rebajar ese mamotreto a algo que se pudiera ver, porque en la radio met\u00edan de todo. Y en la radio era muy popular. Efra\u00edn Arce era muy famoso en esa \u00e9poca.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Y bajo la tierra<\/em> fue un intento del hermano de Santiago Garc\u00eda, quien lo meti\u00f3 a lo del cine, porque le gustaba un poco el teatro tambi\u00e9n. \u00c9l trabajaba en la IBM, ten\u00eda un puesto muy bueno, ten\u00eda su carrazo y su casa, y Santiago le dijo \u201cdeje todas esas vainas absurdas y m\u00e9tase a hacer pel\u00edculas\u201d. Y cogieron un tema que nunca ha sido buena taquilla, el de los mineros, eso siempre ha sido, como dicen los gringos, veneno para la taquilla. Fue una pel\u00edcula muy interesante desde el punto de vista social, porque est\u00e1bamos en unos pueblos mineros tenaces, en Remedios, Antioquia, sitios donde todos los d\u00edas estaban matando gente, pero no por asuntos pol\u00edticos, sino simplemente \u201cporque no me gusta su cara\u201d. Y como nosotros trabaj\u00e1bamos en esa \u00e9poca como si estuvi\u00e9ramos haciendo teatro\u2026 Es que uno tiene que saber c\u00f3mo es que viven los del teatro, que viven de la nada, y por eso no es problema cuando uno necesita reunir gente que quiera colaborar: va y re\u00fane un poco de teatreros y todos colaboran y todos hacen de todo, est\u00e1n entrenados en todo, hacen tramoya, saben actuar, saben hacer vestuario, maquillaje, son muy \u00fatiles para un proyecto. Pero esta pel\u00edcula fue un desastre, el pobre Arturo Garc\u00eda perdi\u00f3 todo, el BMW, la casa, el trabajo, perdi\u00f3 todo, eso era tenaz, ah\u00ed se jugaba casi a perder.<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p>&#8230; por eso no es problema cuando uno necesita reunir gente que quiera colaborar: va y re\u00fane un poco de teatreros y todos colaboran y todos hacen de todo, est\u00e1n entrenados en todo, hacen tramoya, saben actuar, saben hacer vestuario, maquillaje, son muy \u00fatiles para un proyecto.<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Luego busc\u00f3 por el lado de la comedia con <\/em>Fin de semana, <em>uno de los cap\u00edtulos de<\/em> Una tarde\u2026 un lunes\u2026 <em>(1972), \u00bfc\u00f3mo asumi\u00f3 ese giro y, sobre todo, para ponerla entre los dos cap\u00edtulos de Alberto Giraldo que, pr\u00e1cticamente, eran cine de vanguardia?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">S\u00ed, eso era un ensayo hacia a la comedia que luego hice que fue <em>Pr\u00e9stame tu marido<\/em> (1973), para ver si con esa pod\u00edamos hacer algo de plata, pero yo qued\u00e9 muy desilusionado, porque en Colombia, fuera de lo que ha hecho Dago Garc\u00eda, quien ha hecho una combinaci\u00f3n muy buena con Caracol, es muy dif\u00edcil ganar con el cine.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Pero <em>Una tarde, un lunes <\/em>fue m\u00e1s que todo impulso de mi socio de aquella \u00e9poca, que era Alberto Giraldo Castro, que me convenci\u00f3 de que hiciera un corto. Y yo quer\u00eda ensayar algo con alguien como Franky Linero, y me invent\u00e9 una cosa muy sencilla, eso no tiene ninguna trascendencia ni nada. Cuando la pel\u00edcula la pasaron a segundo turno, en esos teatros en que daban dos pel\u00edculas en rotativo, teatros de segunda, casi que desbaratan el teatro. Le tuvieron que quitar la primera historia, la que est\u00e1 en blanco y negro, porque por lo menos la otra ten\u00eda los desnudos de Dora Franco, entonces eso aguantaba; y la m\u00eda, como era tan inocua, pues qu\u00e9 carajo. Porque la gente que iba a pel\u00edculas de segundo turno no era el p\u00fablico intelectual ni el cin\u00e9filo, era la gente del pueblo y, si no les gustaba una pel\u00edcula, pues lo dejaban saber.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfPero fue un buen ejercicio para hacer <\/em>Pr\u00e9stame tu marido<em>?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">S\u00ed, me ayud\u00f3 much\u00edsimo, me dio m\u00e1s confianza para hacer esta otra, pero fue otra vez sin un centavo, sin apoyo de nadie y haciendo cooperativa con los actores, pues siempre est\u00e1bamos trabajando sin presupuesto.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfNo tuvo inconvenientes en el paso del realismo social de sus primeras pel\u00edculas al c\u00f3digo de la comedia de consumo que tienen estas otras?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es que la cosa fue al rev\u00e9s, siempre me ha gustado la comedia, pero la comedia fina, porque hay unas comedias que est\u00e1n haciendo en Colombia que dan verg\u00fcenza, es una combinaci\u00f3n del mal gusto revuelto con el mal gusto.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Se extra\u00f1a su ausencia en los cortos del sobreprecio en los a\u00f1os setenta y en FOCINE en los a\u00f1os ochenta. \u00bfPor qu\u00e9 pas\u00f3 esto?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Solo trabaj\u00e9 en una pel\u00edcula de Antonio Monta\u00f1a sobre el grabador Antonio Roda. Y fue porque era un trabajo art\u00edstico, bonito, y yo le colabor\u00e9 haciendo la c\u00e1mara y con el montaje. Pero el resto de las cosas eran muy malas, verdaderamente fue de lo peor que le haya pasado al cine colombiano. No particip\u00e9 en el sobreprecio porque me pareci\u00f3 que eso era prostituirse; y tampoco particip\u00e9 en pel\u00edculas de FOCINE porque le exig\u00edan a uno que ten\u00eda que hipotecar la casa y hubo muchos problemas con eso. La \u00fanica que s\u00e9 que trat\u00f3 de devolver la plata de alguna forma, con trabajo y todo eso, fue Camila Loboguerrero. Pero el resto, todos se hicieron los pendejos y no pagaron, igual que los distribuidores y exhibidores, y por eso FOCINE fue un desastre. Y otro problema de FOCINE fue creer que ganarse premios en festivales era tan importante como ganarse el p\u00fablico, y eso es algo que yo no creo, para m\u00ed el p\u00fablico es muy importante, porque es el que paga y el que permite que el cine tenga fondos para poder seguir.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Pr\u00e1cticamente dej\u00f3 el cine y se dedic\u00f3 a la publicidad, pero en alg\u00fan momento intent\u00f3 con la televisi\u00f3n, \u00bfC\u00f3mo le fue en ese medio?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">La televisi\u00f3n fue el peor ejercicio que yo hice. Hacer televisi\u00f3n es complicado, ayuda mucho desde el punto de vista t\u00e9cnico, uno tiene que pensar muy r\u00e1pido, tiene que tomar decisiones inmediatas, pero tambi\u00e9n hacer escenas que a uno no le gustan y, definitivamente, hacer una telenovela es un martirio absoluto, porque es repetir las mismas escenas con diferentes actores o repetir los mismos actores con diferentes escenas. Creo que es que es un sistema inflado que para m\u00ed nunca ha tenido cabida. Hoy en d\u00eda las miniseries, que no son muy largas, han cubierto ese espacio de ese tipo de relatos m\u00e1s largos, porque han permitido que una historia que tiene buenos personajes y tiene un buen desarrollo se pueda hacer bien, se pueda hacer con decoro, pero ya cuando le alargas a cincuenta, cien o ciento veinte cap\u00edtulos, eso es un martirio.<\/p>\r\n\r\n\r\n\r\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\r\n<p>&#8230; hacer una telenovela es un martirio absoluto, porque es repetir las mismas escenas con diferentes actores o repetir los mismos actores con diferentes escenas.<\/p>\r\n<\/blockquote>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Mucho despu\u00e9s retom\u00f3 su contacto con el cine a partir de unos documentales sobre la historia del cine nacional. \u00bfC\u00f3mo fue esa experiencia?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Eso es algo que nunca hab\u00eda tomado en consideraci\u00f3n, pero desde que empec\u00e9 con Patrimonio F\u00edlmico Colombiano, pude ver la importancia de los materiales de lo que se va perdiendo, de lo que debe quedar para futuras generaciones, entonces me entr\u00f3 una nueva vida para ver el cine, eso de Patrimonio fue incre\u00edble. Era la \u00e9poca en que estaba Jorge Nieto, que hab\u00eda hecho una serie de entrevistas, como a la actriz de <em>Mar\u00eda<\/em> o al cu\u00f1ado de M\u00e1ximo Calvo, y yo utilic\u00e9 ese material. Para m\u00ed fue un gran aprendizaje, adem\u00e1s, con muy poco material f\u00edlmico, porque ya no exist\u00eda, de algunas pel\u00edculas hab\u00eda un fotograma o ninguno. Quiero terminar esos <em>70 a\u00f1os de sue\u00f1os<\/em>, que es el documental donde resumo la historia del cine colombiano hasta 1970, como un largometraje, con una segunda parte, que ser\u00edan los siguientes cincuenta a\u00f1os, con el sobreprecio, FOCINE, Colcultura y la Ley de cine.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>Es de p\u00fablico conocimiento que usted es muy cr\u00edtico con de la Ley de cine y el FDC. \u00bfQu\u00e9 es lo que m\u00e1s les cuestiona?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Desde que empez\u00f3 la Ley de cine se han hecho unas 160 \u00f3peras primas y ponte a ver cu\u00e1ntos han seguido a una segunda pel\u00edcula, casi nada. \u00bfQu\u00e9 pasa? Esto fue hecho fue para fomentar el cine y lo que m\u00e1s vale en cualquier cinematograf\u00eda es la continuidad de los directores, en otros pa\u00edses los directores pueden tener una filmograf\u00eda, y estos aqu\u00ed: primera y \u00faltima pel\u00edcula.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>De su relaci\u00f3n con el cine le queda la cin\u00e9fila \u00bfCierto?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Es que siempre me ha fascinado el cine, pero todo tipo de cine, aunque lo que s\u00ed no soy es esnobista, al contrario, cuando me llega una pel\u00edcula diciendo que es \u201cla ganadora en Cannes\u201d, yo digo: otro ladrillo (risas). A m\u00ed me gusta el buen cine, los que son casi mis \u00eddolos son los hermanos Cohen. No me gusta tanto la parte de la exageraci\u00f3n de la violencia, la parte cruda y con demasiada sangre, eso me molesta, no es lo m\u00edo, porque yo s\u00e9 que eso se puede mostrar de otra forma, pero son unos maestros en hacer personajes, en plantear situaciones, en verdaderamente meterte en un mundo muy especial de ellos, no hay nadie m\u00e1s igual a ellos.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Yo visito mucho los sitios piratas, tengo una colecci\u00f3n y todas las noches me veo una pel\u00edcula, religiosamente, sea la que sea, es una rutina. Tengo como 740 pel\u00edculas esperando. Entonces siempre tengo las \u00faltimas pel\u00edculas, porque todo se consigue en internet. Aunque a veces prefiero repetirme una pel\u00edcula cl\u00e1sica que ver algo de ahora. Pero desde que empez\u00f3 la pandemia se han multiplicado las pel\u00edculas en internet, y a veces me bajo seis o siete pel\u00edculas al d\u00eda.<\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\"><em>\u00bfC\u00f3mo ser\u00eda una mirada en retrospectiva a su carrera?<\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Yo, b\u00e1sicamente, ejerc\u00ed como director de cine y cinematografista unos trece a\u00f1os, los a\u00f1os sesenta y los primeros a\u00f1os de los setenta. Y ah\u00ed tom\u00e9 la decisi\u00f3n de abandonarlo. Fue con la mala situaci\u00f3n de <em>Pr\u00e9stame tu marido<\/em>, que no pudo hacer plata siendo algo que deb\u00eda hacer mucha plata, porque el medio no da y en esa \u00e9poca hab\u00eda un monopolio del cine mexicano que nunca se menciona en ning\u00fan lado, pero era un monopolio tenaz. Luego vinieron mis a\u00f1os de trabajos en comerciales, que eran para sobrevivir, y algo de teatro y un poquito de televisi\u00f3n. Y despu\u00e9s fue ya como un observador, porque tambi\u00e9n entr\u00e9 a la junta de clasificaci\u00f3n, que, adem\u00e1s, tambi\u00e9n era muy jarto, porque a veces te tocaban tres o cuatro pel\u00edculas seguidas y, al final, ya uno ni se acordaba de cu\u00e1l era la primera pel\u00edcula que te hab\u00edas visto. Entonces despu\u00e9s entr\u00f3 la parte nost\u00e1lgica, con los documentales sobre la historia del cine de Colombia, porque me parece muy importante dejar para futuras generaciones todo lo que se ha podido hacer y, claro, todo lo que puede hacer uno ahora en su m\u00e1quina\u2026 si yo hubiera tenido esto (se\u00f1ala su computador y la pantalla a la que le habla) habr\u00eda sido otro cuento.<\/p>\r\n\r\n\r\n&nbsp;\r\n\r\n<a href=\"http:\/\/vartexmedellin.co\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-2965 size-full\" src=\"http:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/VARTEX-9_2021.png\" alt=\"\" width=\"660\" height=\"297\" srcset=\"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/VARTEX-9_2021.png 660w, https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/VARTEX-9_2021-300x135.png 300w, https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/VARTEX-9_2021-480x216.png 480w\" sizes=\"auto, (max-width: 660px) 100vw, 660px\" \/><\/a>\r\n\r\n&nbsp;","protected":false},"excerpt":{"rendered":"<p>Oswaldo Osorio&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-2793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-entrevistas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Entrevista a Julio Luzardo - CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Entrevista a Julio Luzardo - CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Oswaldo Osorio...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/\" \/>\n<meta property=\"og:site_name\" content=\"CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-17T22:05:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-19T22:03:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/Julio-Luzardo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"headline\":\"Entrevista a Julio Luzardo\",\"datePublished\":\"2021-04-17T22:05:13+00:00\",\"dateModified\":\"2021-04-19T22:03:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/\"},\"wordCount\":3356,\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/04\\\/Julio-Luzardo.jpg\",\"articleSection\":[\"Entrevistas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/\",\"name\":\"Entrevista a Julio Luzardo - CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/04\\\/Julio-Luzardo.jpg\",\"datePublished\":\"2021-04-17T22:05:13+00:00\",\"dateModified\":\"2021-04-19T22:03:09+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/04\\\/Julio-Luzardo.jpg\",\"contentUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2021\\\/04\\\/Julio-Luzardo.jpg\",\"width\":1024,\"height\":683},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/entrevista-julio-luzardo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Entrevista a Julio Luzardo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/#website\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/\",\"name\":\"CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n\",\"description\":\"Revista de Cine Colombiano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/canaguaro.cinefagos.net\"],\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n02\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Entrevista a Julio Luzardo - CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/","og_locale":"en_US","og_type":"article","og_title":"Entrevista a Julio Luzardo - CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n","og_description":"Oswaldo Osorio...","og_url":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/","og_site_name":"CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n","article_published_time":"2021-04-17T22:05:13+00:00","article_modified_time":"2021-04-19T22:03:09+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/Julio-Luzardo.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#article","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/"},"author":{"name":"admin","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"headline":"Entrevista a Julio Luzardo","datePublished":"2021-04-17T22:05:13+00:00","dateModified":"2021-04-19T22:03:09+00:00","mainEntityOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/"},"wordCount":3356,"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/Julio-Luzardo.jpg","articleSection":["Entrevistas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/","url":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/","name":"Entrevista a Julio Luzardo - CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#primaryimage"},"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/Julio-Luzardo.jpg","datePublished":"2021-04-17T22:05:13+00:00","dateModified":"2021-04-19T22:03:09+00:00","author":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"breadcrumb":{"@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#primaryimage","url":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/Julio-Luzardo.jpg","contentUrl":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-content\/uploads\/sites\/3\/2021\/04\/Julio-Luzardo.jpg","width":1024,"height":683},{"@type":"BreadcrumbList","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/entrevista-julio-luzardo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canaguaro.cinefagos.net\/n02\/"},{"@type":"ListItem","position":2,"name":"Entrevista a Julio Luzardo"}]},{"@type":"WebSite","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/#website","url":"https:\/\/canaguaro.cinefagos.net\/n02\/","name":"CANAGUARO - Revista de cine colombiano - Segunda edici\u00f3n","description":"Revista de Cine Colombiano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canaguaro.cinefagos.net\/n02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/canaguaro.cinefagos.net\/n02\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/canaguaro.cinefagos.net"],"url":"https:\/\/canaguaro.cinefagos.net\/n02\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/posts\/2793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/comments?post=2793"}],"version-history":[{"count":8,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/posts\/2793\/revisions"}],"predecessor-version":[{"id":2993,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/posts\/2793\/revisions\/2993"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/media\/2802"}],"wp:attachment":[{"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/media?parent=2793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/categories?post=2793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n02\/wp-json\/wp\/v2\/tags?post=2793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}