{"id":1888,"date":"2022-12-12T05:07:25","date_gmt":"2022-12-12T05:07:25","guid":{"rendered":"https:\/\/canaguaro.cinefagos.net\/n07\/?p=1888"},"modified":"2022-12-12T05:08:25","modified_gmt":"2022-12-12T05:08:25","slug":"las-medias-blancas-y-el-punk-bien-espeso","status":"publish","type":"post","link":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/","title":{"rendered":"Las medias blancas y el punk bien espeso"},"content":{"rendered":"<p class=\"autor\">Jhon Cristian A. Ortega Erazo<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42 aligncenter\" src=\"https:\/\/canaguaro.cinefagos.net\/n05\/wp-content\/uploads\/sites\/7\/2021\/08\/sep.png\" alt=\"\" width=\"22\" height=\"8\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"entradilla\"><em>Rodrigo D: No futuro <\/em>(V\u00edctor Gaviria, 1990) y<em> Medias Blancas <\/em>(Andr\u00e9s Isaza, 2017), dos relatos de juventudes diametralmente opuestas, pero bajo el mismo sentido, buscar suplir un vac\u00edo, familiar tal vez. La radiograf\u00eda nacional de nuestro cine y nuestra historia pareciera que nos tratara de susurrar algo aunque sea m\u00ednimamente, que nos parece contar que nuestra sociedad ha sido hu\u00e9rfana, desamparada y tra\u00edda de otro lugar, que busca en algo o alguien, una figura parental, que no se nos separe y que nos sepa guiar para que, as\u00ed, podamos estar y m\u00e1s tranquilamente aparentar que no parecemos tan confundidos como en verdad constantemente lo estamos, a la deriva, a la espera de no caer, de no ceder ante la imagen de un estado fallido.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 consecuencias traer\u00eda ese tipo de sociedad, adem\u00e1s de aquello de ser una colectividad conflictiva por no sabernos o ponernos de acuerdo en c\u00f3mo organizarnos entre tanta pluralidad? \u2013de gente tan distinta de ser y ver las cosas\u2013 Posteriormente, \u00bfesto de qu\u00e9 manera influir\u00e1 en la filmograf\u00eda nacional? \u00bfSe habr\u00eda podido dar entonces un cortometraje como <em>Medias Blancas<\/em> unas d\u00e9cadas atr\u00e1s en este pa\u00eds? \u00bfen Bogot\u00e1 o en otro lugar? en definitiva, \u00bfen otro tiempo diferente a este? Probablemente s\u00ed, pero seguramente ya no ser\u00eda colombiano. Quiz\u00e1 sus elementos, como la puesta en escena realista de la simb\u00f3lica intenci\u00f3n de Ignacio por perderse en el tiempo y su hast\u00edo por la vida actual, habr\u00edan sido elementos y temas concebidos en otra latitud del planeta, pues la simpleza de su premisa encierra una condici\u00f3n universal que todo ser vivo experimenta, esa idea de que todos vamos a crecer, que todos nos hacemos mayores, que las cosas cambian, y que a veces, aquellas cuestiones, sumergir\u00edan a algunos cuerpos de bilis negra, seg\u00fan Hip\u00f3crates, en una nost\u00e1lgica y melanc\u00f3lica tristeza por ver y sentir un pasado que constantemente a\u00f1oran; ser\u00edan sucesos epis\u00f3dicos que, por su puesto, podr\u00eda suceder a otro humano en otra regi\u00f3n del planeta, el cual \u2013hasta donde alcanzo a conocer\u2013 no fue captado en un cortometraje pero que, aun as\u00ed, tendr\u00edan la posibilidad y las circunstancias de ser y hacerlo si nos referimos a casos como el europeo o estadounidense.<\/p>\n<p>&nbsp;<\/p>\n<p>Esto no solo porque nuestra tradici\u00f3n cinematogr\u00e1fica en el siglo XX no ten\u00eda \u2013y de por s\u00ed a\u00fan no tiene\u2013\u00a0 un portento industrial cinematogr\u00e1fico fraguado con el tiempo o porque el argumento de un chico desplaz\u00e1ndose a otra ciudad para estudiar en la universidad no fuera una realidad tan com\u00fan como lo es ahora en el presente, sino porque adem\u00e1s, nuestra concepci\u00f3n cinematogr\u00e1fica no ten\u00eda espacio en su cabeza como para representar la vida cotidiana con su reflexi\u00f3n sobre la vida m\u00e1s cercana a trav\u00e9s de la conjunci\u00f3n expresiva de sus componentes, imagen y sonido.\u00a0 Habr\u00eda que esperar hasta superar la \u00e9poca bambuquera del cine colombiano y llegar a entender el cine como un lenguaje m\u00e1s establecido. Dos acotaciones aqu\u00ed nos evidencian nuestra particular relaci\u00f3n nacional con el cine respecto al desarrollo de otros pa\u00edses con este arte: Nuestra atrasada e intermitente continuidad cinematogr\u00e1fica y lo que ha sido nuestra inmediata realidad como pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p>Al no tener cabeza y certeza de representar al colombiano estudiante joven com\u00fan y su malestar m\u00e1s interno en d\u00e9cadas pasadas, cuando se comenz\u00f3 a conocer mejor la t\u00e9cnica cinematogr\u00e1fica, era un asunto m\u00e1s de incidencias contextuales m\u00e1s no de querer no hacerlo. Es decir, \u00bfqu\u00e9 otra cosa m\u00e1s importante, urgente y preocupante era para los realizadores de esa \u00e9poca hablar sino de la violencia pol\u00edtica y barrial entrometida en casi todos los asuntos sociales de esa \u00e9poca?<\/p>\n<p>&nbsp;<\/p>\n<p>Si el ejercicio de comprender la violencia estaba desamparado y mal saneado por la mayor\u00eda de los medios de comunicaci\u00f3n, era entonces una necesidad imperante del cine tratar de establecer un di\u00e1logo, en mejor de los casos reflexivo, donde se pudiera tratar la violencia desde lo argumental y con un tipo de suerte, dejarle un sabor distinto al espectador acostumbrado a la violencia de noticieros. <em>C\u00f3ndores no entierran todos los d\u00edas <\/em>(1984) da cuenta de ese esfuerzo en el caso cinematogr\u00e1fico, tanto que el autor de la novela original, Gustavo \u00c1lvarez Gardeazabal, esperaba poder evitar nuevos conflictos al tratar de escribir su obra. Este esfuerzo sucede una vez se ten\u00eda dominio del oficio del cine, cuando entonces se pudieron escuchar los buenos ecos de otros tempranos denuedos que hablar\u00edan sobre la realidad acuciante del pa\u00eds. Julio Luzardo y Jos\u00e9 Mar\u00eda Arzuaga estar\u00edan dando voz a esa violencia miserabilista del abandono estatal de los a\u00f1os sesenta; siendo esta violencia semilla que, como sucedi\u00f3 con la historia pol\u00edtica y social de Colombia, germinar\u00eda y terminar\u00eda siendo tambi\u00e9n parte de la trayectoria del cine colombiano, tray\u00e9ndonos consigo una de las m\u00e1s grandes narrativas de nuestro pa\u00eds, la violencia.<\/p>\n<blockquote>\n<p class=\"destacado\">Dos acotaciones aqu\u00ed nos evidencian nuestra particular relaci\u00f3n nacional con el cine respecto al desarrollo de otros pa\u00edses con este arte: Nuestra atrasada e intermitente continuidad cinematogr\u00e1fica y lo que ha sido nuestra inmediata realidad como pa\u00eds.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>No es gratuito, por tanto, tener en nuestra filmograf\u00eda nacional pel\u00edculas como <em>Rodrigo D<\/em>, pues dan cuenta de una concatenaci\u00f3n de violencias pasadas hasta ese momento, es decir, como si aquella fuera la secuela de los anteriores episodios de la historia de la violencia en Colombia. Mostr\u00e1ndonos en esta ocasi\u00f3n las consecuencias de esa violencia m\u00e1s inmediata de aquel tiempo, la guerrillera, la cual venia teji\u00e9ndose a\u00f1os atr\u00e1s fruto de otras violencias y que dejar\u00eda, junto a otras din\u00e1micas relacionadas, un vac\u00edo de oportunidades que ser\u00edan suplidas eventualmente por el narcotr\u00e1fico y las bandas criminales. \u00a0El filme de Gaviria nos daba pistas de lo que fue esa violencia bipartidista \u2013engendrada quiz\u00e1 muchos a\u00f1os antes del bogotazo\u2013 y que, en s\u00ed, era la misma violencia de ese entonces pero ahora pose\u00eda una cara diferente, lo cual no nos indicaba necesariamente que el anterior rostro se hab\u00eda extinguido, o por lo menos no del todo, sino que varias facetas de la misma violencia pueden vivir contempor\u00e1neamente.<\/p>\n<p>&nbsp;<\/p>\n<p>No es raro esperar, entonces, que una vez el lenguaje cinematogr\u00e1fico fuera dominado un poco m\u00e1s en Colombia, fuera la narrativa de la violencia uno de sus grandes temas, pues no hab\u00eda realidad m\u00e1s acuciante que la vivida en aquella \u00e9poca y que, as\u00ed como la violencia fue propag\u00e1ndose, evolucionando, escalando y transform\u00e1ndose, as\u00ed lo hizo \u2013pero quiz\u00e1 no paralelamente y no tan afortunadamente\u2013 el cine colombiano.<\/p>\n<p>&nbsp;<\/p>\n<p>La violencia primigenia, y de forma distinta, presentada en la disputa entre liberales y conservadores \u2013 y el cine nacional a\u00fan tiene sus deudas con este periodo\u2013 en contraposici\u00f3n con la violencia evolucionada perteneciente a la vida pobre y urbana en <em>Rodrigo D<\/em>, dar\u00eda cuenta de un proceso en la trayectoria del pa\u00eds, donde quiz\u00e1 el resultado de esa arrogancia de aquella c\u00fapula plutocr\u00e1tica promulgante de la ineficiencia del estado, trajera consigo el abandono y la falta de oportunidades en buena parte de la poblaci\u00f3n urbana y, sobre todo, rural colombiana, que, en consecuencia, forjar\u00eda a los civiles rebeldes padecientes de ese malestar inducido por la indiferencia estatal; naciendo as\u00ed los decididos grupos guerrilleros, desatando una oleada de guerras internas parciales y luego completas dentro del pa\u00eds, la cual ver\u00edamos en sus consecuencias, como el desplazamiento y la falta de oportunidades y su profusa brecha. \u00bfQu\u00e9 quedaba hasta ahora de todo eso? pues un entorno hostil y una realidad como la de Rodrigo, insatisfecho y sin futuro, en una Colombia urbana de los ochenta. Una cruda realidad pandillera palpitante que mostraba lo que era ser pobre y joven en la ciudad de Medell\u00edn. He aqu\u00ed una nueva cara de la violencia gestada por lo menos desde el conflicto estado-guerrilla y m\u00e1s antes, entre liberales y conservadores.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfQu\u00e9 ha pasado, entonces, con la filmograf\u00eda de nuestro pa\u00eds como para traernos ahora historias m\u00e1s \u00edntimas como la presentada en <em>Medias Blancas<\/em>? De un tiempo para ac\u00e1, aunque la violencia sigue a\u00fan viva, pues arde con la misma complejidad, ahora lo hace un poco menos, por lo que su menor intensidad ha dado aire y espacio para pensar y dar nuevos relatos alejados de la violencia asfixiante que significaba en otros a\u00f1os las turbulentas d\u00e9cadas pasadas. Esto sucede al tiempo que una mayor parte de la poblaci\u00f3n ha tenido acceso a la educaci\u00f3n y que eventualmente ha proliferado, a su vez, una nueva camada de realizadores que han sido formados en escuela de cine o afines y que, naturalmente, son pertenecientes a una generaci\u00f3n m\u00e1s nativa al entorno audiovisual y digital, lo que posibilitar\u00eda las nuevas maneras de mirar, relatar y crear, deslig\u00e1ndose del gran tema colombiano, y de la esquem\u00e1tica f\u00f3rmula industrial de hacer cine.<\/p>\n<blockquote>\n<p class=\"destacado\">\u00bfQu\u00e9 quedaba hasta ahora de todo eso? pues un entorno hostil y una realidad como la de Rodrigo, insatisfecho y sin futuro, en una Colombia urbana de los ochenta.<\/p>\n<\/blockquote>\n<p>&nbsp;<\/p>\n<p>Como vemos, en el transcurso de nuestra historia fue casi inevitable no haber llegado a tener en nuestra filmograf\u00eda nacional una pel\u00edcula como <em>Rodrigo D<\/em> para ir paulatinamente desplaz\u00e1ndose a otros linderos, donde se consideran otros conceptos y c\u00e1nones conjeturados, a fin de lograr contundencia desde la eficiente y correcta ejecuci\u00f3n de una narraci\u00f3n alternativa<a href=\"#_ftn1\" name=\"_ftnref1\"><sup><sup>[1]<\/sup><\/sup><\/a> para una realidad menos estridente pero igual de sincera, humana y plausible.<\/p>\n<p>&nbsp;<\/p>\n<p>Por tanto, ser una sociedad que desde un comienzo invisibilizaba a sus otras contrapartes en consecuci\u00f3n del ordenamiento territorial, nos traer\u00eda una herencia y una cultura violenta, cuya prolongaci\u00f3n azuzar\u00eda el caldo de malestar que se cocinar\u00eda a\u00fan m\u00e1s entrando en el siglo XX y que rebosar\u00eda la olla en 1948 con la muerte de Jorge Eliecer Gait\u00e1n. Sucesos que pidieron un tratamiento y un intento de explicaci\u00f3n, la cual encontrar\u00eda en el cine una forma de expresi\u00f3n. Es as\u00ed como estos sucesos influir\u00edan en la filmograf\u00eda nacional, y una muestra de ello es que una idea como <em>Medias Blancas<\/em> no se habr\u00eda podido dar en otras d\u00e9cadas, pues la realidad campesina de la \u00e9poca y su apremiante violencia no daba espacio para otros argumentos \u2013el de un joven estudiando en una ciudad ajena\u2013 y, sumado a una precaria formaci\u00f3n en la t\u00e9cnica cinematogr\u00e1fica, har\u00edan imposible una reflexi\u00f3n audiovisual del tema.<\/p>\n<p>&nbsp;<\/p>\n<p>Por ello, este texto se escribi\u00f3 bajo la idea de que la violencia fuera una gran mara\u00f1a, pero contenido dentro de un cuerpo firme de una serpiente \u2013l\u00ednea recta\u2013 en la cual se ha ido recorriendo su piel con cada pel\u00edcula que se hizo en su historia, de esa manera se desplaza el cine nacional sobre los distintos cent\u00edmetros de esa piel escamosa, enmarcando las evolucionadas facetas de la violencia a trav\u00e9s de las varias distancias de ese cuerpo \u2013su equivalencia es el tiempo\u2013 con la idea de que, quiz\u00e1, llegaremos hasta al final de su cabeza. Una vez all\u00ed, apreciar su cuerpo, se\u00f1al de no olvido, para la no repetici\u00f3n de este tipo de violencia.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"#_ftnref1\" name=\"_ftn1\"><sup><sup>[1]<\/sup><\/sup><\/a> Ejemplos con estas narrativas alternativas la encontramos, claro, en el cortometraje referenciado de este texto, <em>Medias blancas<\/em>, pero tambi\u00e9n en otras pel\u00edculas como <em>La tierra y la sombra <\/em>(C\u00e9sar Acevedo, 2015) <em>El vuelco del cangrejo<\/em> (\u00d3scar Ruiz Navia, 2009); <em>El Colombian Dream<\/em> (Felipe Aljure, 2006), <em>Los extra\u00f1os presagios de Le\u00f3n Prozak<\/em> (Carlos Santa, 2010), <em>Violeta de mil colores<\/em> (Harold Trompetero, 2006), <em>La sirga<\/em> (William vega, 2012), <em>Cazando luci\u00e9rnagas<\/em> (Roberto Flores Prieto, 2013), entre otras.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jhon Cristian A. Ortega Erazo<\/p>\n","protected":false},"author":1,"featured_media":1889,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-1888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-articulos-y-ensayos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Las medias blancas y el punk bien espeso - CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las medias blancas y el punk bien espeso - CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n\" \/>\n<meta property=\"og:description\" content=\"Jhon Cristian A. Ortega Erazo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/\" \/>\n<meta property=\"og:site_name\" content=\"CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-12T05:07:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-12T05:08:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/canaguaro.cinefagos.net\/n07\/wp-content\/uploads\/sites\/9\/2022\/12\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"headline\":\"Las medias blancas y el punk bien espeso\",\"datePublished\":\"2022-12-12T05:07:25+00:00\",\"dateModified\":\"2022-12-12T05:08:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/\"},\"wordCount\":2060,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/12\\\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg\",\"articleSection\":[\"Art\u00edculos y ensayos\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/\",\"name\":\"Las medias blancas y el punk bien espeso - CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/12\\\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg\",\"datePublished\":\"2022-12-12T05:07:25+00:00\",\"dateModified\":\"2022-12-12T05:08:25+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/12\\\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg\",\"contentUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2022\\\/12\\\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg\",\"width\":1920,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/las-medias-blancas-y-el-punk-bien-espeso\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las medias blancas y el punk bien espeso\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/#website\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/\",\"name\":\"CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n\",\"description\":\"Revista de Cine Colombiano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/canaguaro.cinefagos.net\"],\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n07\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las medias blancas y el punk bien espeso - CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/","og_locale":"es_ES","og_type":"article","og_title":"Las medias blancas y el punk bien espeso - CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n","og_description":"Jhon Cristian A. Ortega Erazo","og_url":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/","og_site_name":"CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n","article_published_time":"2022-12-12T05:07:25+00:00","article_modified_time":"2022-12-12T05:08:25+00:00","og_image":[{"width":1920,"height":600,"url":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-content\/uploads\/sites\/9\/2022\/12\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#article","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/"},"author":{"name":"admin","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"headline":"Las medias blancas y el punk bien espeso","datePublished":"2022-12-12T05:07:25+00:00","dateModified":"2022-12-12T05:08:25+00:00","mainEntityOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/"},"wordCount":2060,"commentCount":0,"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-content\/uploads\/sites\/9\/2022\/12\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg","articleSection":["Art\u00edculos y ensayos"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/","url":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/","name":"Las medias blancas y el punk bien espeso - CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#primaryimage"},"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-content\/uploads\/sites\/9\/2022\/12\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg","datePublished":"2022-12-12T05:07:25+00:00","dateModified":"2022-12-12T05:08:25+00:00","author":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"breadcrumb":{"@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#primaryimage","url":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-content\/uploads\/sites\/9\/2022\/12\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg","contentUrl":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-content\/uploads\/sites\/9\/2022\/12\/ARTICULOS-Y-ENSAYOS-Las-medias-blancas-y-el-punk-bien-espeso.jpg","width":1920,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/las-medias-blancas-y-el-punk-bien-espeso\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canaguaro.cinefagos.net\/n07\/"},{"@type":"ListItem","position":2,"name":"Las medias blancas y el punk bien espeso"}]},{"@type":"WebSite","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/#website","url":"https:\/\/canaguaro.cinefagos.net\/n07\/","name":"CANAGUARO - Revista de cine colombiano - S\u00e9ptima edici\u00f3n","description":"Revista de Cine Colombiano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canaguaro.cinefagos.net\/n07\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Person","@id":"https:\/\/canaguaro.cinefagos.net\/n07\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30","name":"admin","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/canaguaro.cinefagos.net"],"url":"https:\/\/canaguaro.cinefagos.net\/n07\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/posts\/1888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/comments?post=1888"}],"version-history":[{"count":3,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/posts\/1888\/revisions"}],"predecessor-version":[{"id":1891,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/posts\/1888\/revisions\/1891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/media\/1889"}],"wp:attachment":[{"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/media?parent=1888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/categories?post=1888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n07\/wp-json\/wp\/v2\/tags?post=1888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}