{"id":568,"date":"2024-05-05T02:18:32","date_gmt":"2024-05-05T02:18:32","guid":{"rendered":"https:\/\/canaguaro.cinefagos.net\/n11\/?p=568"},"modified":"2024-07-12T01:30:00","modified_gmt":"2024-07-12T01:30:00","slug":"el-vaquero-de-emma-rozanski","status":"publish","type":"post","link":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/","title":{"rendered":"El vaquero, de Emma Rozanski"},"content":{"rendered":"<p class=\"autor\">Daniel Tamayo Uribe<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42 aligncenter\" src=\"https:\/\/canaguaro.cinefagos.net\/n05\/wp-content\/uploads\/sites\/7\/2021\/08\/sep.png\" alt=\"\" width=\"22\" height=\"8\" \/><\/p>\n<p><strong>Algunos temas por los que se inquietan algunos cines de hoy<\/strong><\/p>\n<p class=\"entradilla\">La presente publicaci\u00f3n, <em>Canaguaro, revista de cine colombiano<\/em>, como su nombre lo indica, se dedica a abordar <em>cr\u00edticamente<\/em> este cine en general. Pero este enfoque no implica evitar hablar del cine y del mundo externos a Colombia. Es evidente que el pa\u00eds y su cine son como son por la influencia y las relaciones que sostienen con otros cines y otras naciones y pueblos. En este sentido, y a prop\u00f3sito de la pel\u00edcula con la que aqu\u00ed quiero dialogar, me gustar\u00eda mencionar dos pel\u00edculas tambi\u00e9n contempor\u00e1neas que se me vinieron a la imaginaci\u00f3n mientras y luego de ver <em>El vaquero<\/em> (2024) de Emma Rozanski. Se trata de t\u00edtulos conocidos: <em>Perfect days<\/em>, de Wim Wenders (2023) y <em>Los colonos<\/em>, de Felipe G\u00e1lvez (2023).<\/p>\n<p>&nbsp;<\/p>\n<p>Estas pel\u00edculas vienen a cuento, primero, por un rasgo en com\u00fan: involucran el encuentro entre diferentes culturas del mundo. Wenders es un alem\u00e1n que filma en Jap\u00f3n y el protagonista japon\u00e9s es un ferviente fan de la m\u00fasica en ingl\u00e9s; un mexicano, un escoc\u00e9s y un mestizo recorren el territorio que se supone le corresponde a la rep\u00fablica de Chile, pero est\u00e1 habitado por personas que no comparten esa imposici\u00f3n. Segundo, por diferentes elementos, <em>Perfect days<\/em> pone a prueba una forma de vida en la actualidad; y <em>Los colonos<\/em> es una versi\u00f3n contempor\u00e1nea del g\u00e9nero cinematogr\u00e1fico del <em>Western <\/em>(que se fund\u00f3 con la famosa pel\u00edcula gringa <em>The Great Train Robbery<\/em>, de Edwin S. Porter, 1903). Ahora, todo esto tiene que ver con <em>El vaquero<\/em>, pel\u00edcula colombo-brit\u00e1nica, porque all\u00ed se representa una forma de vida que se relaciona con las pel\u00edculas del <em>Western<\/em>, pero se da en una mujer que se encuentra con una yegua cerca del Parque Natural de Chingaza en la zona monta\u00f1osa del centro del pa\u00eds.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sobre la c<em>r\u00edtica<\/em> de <em>El vaquero<\/em>, de Emma Rozanski<\/strong><\/p>\n<p>Puede parecer un capricho haber citado las otras dos pel\u00edculas \u2013y quiz\u00e1s lo es\u2013 pero quise hacerlo para sustentar con un par de ejemplos reconocidos que hay mismas inquietudes que se vienen tratando desde diferentes lugares: c\u00f3mo vivir la fundaci\u00f3n de un territorio y el encuentro intercultural. En este contexto me parece valioso preguntarme, <em>cr\u00edticamente,<\/em> por la pel\u00edcula de Emma. Valga decir que el sentido de \u201clo cr\u00edtico\u201d aqu\u00ed no solo viene del oficio de cr\u00edtica cinematogr\u00e1fica, sino que tambi\u00e9n se inspira en el significado que le dio el fil\u00f3sofo alem\u00e1n del siglo XVIII, Immanuel Kant, a esa forma de pensar. Hacer cr\u00edtica consiste en mirar las condiciones (en que es posible) o los l\u00edmites de determinada cuesti\u00f3n, solo que aqu\u00ed no lo pensar\u00e9 filos\u00f3ficamente sino m\u00e1s bien cotidianamente. No quisiera ponerme en el mal tono de ciertas filosof\u00edas y escrituras ladrilludas y acad\u00e9micas. Prefiero pasear por la obra de Emma y ver qu\u00e9 me surge sobre los temas que mencion\u00e9.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Sensaciones sencillas<\/strong><\/p>\n<p>Bernicia es la m\u00e1s morena de su blanca y femenina familia. Blanca campesina, blanca de pueblo colombiano. Vive con t\u00eda, hermana y sobrinas. Parece la m\u00e1s mechuda de todas y con rasgos ind\u00edgenas en su cuerpo. Es tranquila, callada y amable. En muchos planos abiertos observa y se acerca a la naturaleza. Comienza por lanzarse a meter las narices en la musgosa pared, recoge frutas, se ba\u00f1a en agua fr\u00eda, prende fogatas, come vegetales, riega peque\u00f1as plantas. En planos m\u00e1s cerrados se mete debajo de su cama y mira, con ojos cerrados, las luces coloridas y navide\u00f1as que cuelgan abajo de su colch\u00f3n. Parece una vida en paz y sin turbulencias.<\/p>\n<p>&nbsp;<\/p>\n<p>Un d\u00eda, durante su trabajo en la monta\u00f1a, una yegua negra, cuyo due\u00f1o no se presenta, aparece y no se va. Es este animal el que le pone turbulencia a la serena vida de Bernicia, quien no puede evitar sentirse atra\u00edda por esta bella y misteriosa presencia. Es m\u00e1s callada, menos tranquila e igual de amable que Bernicia. Ambas parecen temerosas y valientes con la vida. En la pel\u00edcula se desarrolla la relaci\u00f3n entre las dos, m\u00e1s desde lo que la mujer siente y comprende de la yegua que desde lo que la equina llega a expresar.<\/p>\n<blockquote class=\"destacado\"><p>En planos m\u00e1s cerrados se mete debajo de su cama y mira, con ojos cerrados, las luces coloridas y navide\u00f1as que cuelgan abajo de su colch\u00f3n. Parece una vida en paz y sin turbulencias.<\/p><\/blockquote>\n<p>En un abandonado y pastoso escenario hecho para llevar a cabo corralejas (en las que nunca he estado pero me parecen una intensa festividad que involucra personas, toros y caballos y no son \u201ccorridas de toros\u201d) Bernicia y su hermana recuerdan haber visto proyectada una pel\u00edcula de vaqueros en dicho lugar. El espacio, como este g\u00e9nero de cine, sigue siendo visitado pero ahora es usado para otra cosa. La inquietud por las pel\u00edculas se manifiesta en acci\u00f3n y fortuna, entonces filmes de <em>Westerns<\/em> en CD llegan a las manos de Bernicia. El blanco y negro es borroso pero se distingue a los vaqueros cabalgando y los tiros retumbando frente a las mujeres que los ven y escuchan.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Diferentes vaqueros<\/strong><\/p>\n<p>Yo no soy el m\u00e1s fan de pel\u00edculas de vaqueros y tampoco el que m\u00e1s sabe de vaqueros en general. En Colombia es usual tener el estereotipo m\u00e1s cercano a estos como hombres \u201cmachotes\u201d agricultores y ganaderos con sombreros, botas y cintur\u00f3n montados a caballo, cual vaquero del oeste de Norteam\u00e9rica. A los colombianos me los imagino rudos, bien carn\u00edvoros, buscando ampliar <em>sus<\/em> tierras y, en muchos casos, metidos en el conflicto violento. Los gringos, parecidos, suelen ser los h\u00e9roes cuyas fechor\u00edas por \u201cla conquista del oeste\u201d se justifican como el precio que se paga por un gran sacrificio. Ambos, con un esp\u00edritu cat\u00f3lico, echan balan con suma facilidad.<\/p>\n<p>&nbsp;<\/p>\n<p>Bernicia llega a vestirse de vaquero con sombrero y todo, cabalga sobre la yegua y podr\u00eda decirse que emigra a un nuevo espacio que no es suyo. A ella las balas no le agradan. Se pregunta si en los <em>Westerns<\/em> no podr\u00edan los vaqueros simplemente dedicarse a cabalgar y contemplar el paisaje. Una amiga le dice que eso ser\u00eda una pel\u00edcula muy aburrida. Tan aburrida como la vida que ella quiere llevar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Masculina y femenina<\/strong><\/p>\n<p>Me recuerda un poco al protagonista de <em>Perfect days<\/em>. A Bernicia tambi\u00e9n la veo con un esp\u00edritu m\u00e1s budista, quiz\u00e1s estoico. A diferencia del japon\u00e9s, ella es vaquera y est\u00e1 lejos de los limpios ba\u00f1os que debe limpiar el se\u00f1or. Se encuentra en un espacio m\u00e1s solo que donde vive este, pero est\u00e1 m\u00e1s acompa\u00f1ada. En vez de ser una f\u00e9rrea consumidora cultural, tiene de sobra con sus luces de colores, una arm\u00f3nica y m\u00fasica dieg\u00e9tica. Ella no parece buscar un hombre, en cambio el limpiador de inodoros se resiste a las mujeres.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>Hay muchas pel\u00edculas en las que el ambiente que habitan los hombres es uno lleno de brutalidad, sufrimiento, honor y deshonor. Echan bala a la lata o cosas semejantes. Usualmente matan o son asesinados, literal o metaf\u00f3ricamente. Hay grandes logros y abismales ca\u00eddas. Alianzas y traiciones. Tesoros encontrados y heridas como marcas. Por el contrario<strong>, <\/strong>en <em>El vaquero<\/em> hay en su mayor\u00eda personajes femeninos. La atm\u00f3sfera es m\u00e1s bien amable y tierna. Lo l\u00fadico se mezcla con lo infantil y la nobleza con un sutil coraje. El honor se cambia por el cuidado. En vez de balas, \u00bfqu\u00e9? Son pocos los hombres que aparecen o que tienen importancia a\u00fan sin hacerlo. Y all\u00ed resulta interesante que el due\u00f1o de esta yegua sea un hombre de m\u00e1s de cien a\u00f1os. Parece un viejo ancestro que, entre otras cosas, dej\u00f3 este animal hembra cuya irrupci\u00f3n es el punto de inflexi\u00f3n de la trama. En vez de balas otras im\u00e1genes, las de los disparos de la c\u00e1mara.<\/p>\n<blockquote class=\"destacado\"><p>&#8230; en <em>El vaquero<\/em> hay en su mayor\u00eda personajes femeninos. La atm\u00f3sfera es m\u00e1s bien amable y tierna. Lo l\u00fadico se mezcla con lo infantil y la nobleza con un sutil coraje. El honor se cambia por el cuidado.<\/p><\/blockquote>\n<p>Una pel\u00edcula diferente. La forma masculina interroga por la violencia. Aunque busca alternativas a\u00fan no encuentra. \u00bfSer\u00e1 que su cosmos es tan brutal que por eso termina en m\u00e1s violencia o en la resignaci\u00f3n de la misma? Asume la muerte violenta o se queda en la cobard\u00eda. Parece una condena, pero los hombres siguen, todav\u00eda cosechan cosas que pueden ser legado. La forma femenina, a su vez comparte este mundo de los hombres pero no se organiza igual. Por su parte, alegra o entristece. Bernicia toma los frutos del entorno. En la forma femenina la brutalidad no es violenta y la condena es tan vieja que como que ya le est\u00e1n encontrando ant\u00eddoto. Ellas tambi\u00e9n son conocedoras de venenos y remedios. Toca es en dosis apropiadas. Como el justo whisky que comparte Bernicia con su hermana y un viajero alem\u00e1n. Disfruta sin guayabo con el extranjero que s\u00ed termina con la cabeza algo dolida. Y con esa misma mesura, de a poquitos, la mujer se va yendo de un lugar para otro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La fundaci\u00f3n de un viejo territorio <\/strong><\/p>\n<p>En <em>Los Colonos<\/em> volvemos m\u00e1s de cien a\u00f1os atr\u00e1s en la historia de Chile. La traves\u00eda por los territorios va mostrando los diferentes precios que tuvo una particular colonizaci\u00f3n. La c\u00e1mara registra la mirada del resentimiento que no olvida. Hablaba con un amigo, como buenos hombres que somos, del precio que tiene fundar una naci\u00f3n. \u00c9l dec\u00eda que el precio es el olvido. Pero si no hay ese olvido, eso es que alguien no se ha decidido a pagar el precio. La fundaci\u00f3n tambalea y con esta los cimientos de la naci\u00f3n en el territorio.<\/p>\n<p>&nbsp;<\/p>\n<p>En la pel\u00edcula de Emma, cien a\u00f1os o m\u00e1s podr\u00eda tener la casa del due\u00f1o de la yegua. En conformidad, la yegua puede ser un emisario m\u00edtico. Una yegua olvidada entre los caballos divinos. Esta no tiene un costo monetario. <em>Simplemente<\/em> es acercarse a ella. Pero nadie lo hace, solo Bernicia. Lo que tiene precio es la casa y el territorio dejados por el se\u00f1or centenario. All\u00ed todo sigue igual, excepto que ya no est\u00e1 quien all\u00ed habitaba. Algo parecido podr\u00eda decirse con los territorios de los nativos ind\u00edgenas. O al menos es lo que se pretendi\u00f3 en que pudiera decirse. Y como en dichas tierras, los propietarios son otros. En la casa de la yegua es due\u00f1o un viejo campesino de sombrero. Este no le cobraba dinero al otro anciano por su edad. A Bernicia s\u00ed se lo pide. Llegan a un acuerdo sin destierros, sin guerras. Una nueva fundaci\u00f3n. El viejo territorio es el mismo, pero la vida de la vaquera, en caso de consumarse, le da otro sentido. No va con el r\u00f3tulo de \u201cnaci\u00f3n\u201d sino de \u201chogar\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Tri\u00e1ngulo de generaciones<\/strong><\/p>\n<p>Aunque no lo parezca, la amable determinaci\u00f3n de Bernicia puede ser una afrenta. Tan es as\u00ed que su hermana le dice que tenga cuidado, porque en el pueblo podr\u00edan llegar a burlarse de su vestimenta vaqueresca. Igualmente su t\u00eda le pone reparos por las actitudes y decisiones \u201cextra\u00f1as\u201d que est\u00e1 adoptando y que atentan contra la estabilidad de la familia. No tiene inter\u00e9s en vivir como tradicionalmente se dice que deben o deb\u00edan vivir las mujeres. Los fieles ortodoxos de los <em>Westerns<\/em> no incluyen esta entre sus adoradas pel\u00edculas.<\/p>\n<p>&nbsp;<\/p>\n<p>A sus peque\u00f1as sobrinas Bernicia les ense\u00f1a a regar su vida diferente que ella quiere llevar. Hay que regar con suficiente agua pero no demasiada para no ahogarla. Sin inter\u00e9s en pareja o ni\u00f1os, entre \u201cel mundo\u201d y el verde que las rodea a ella y la yegua. No abandona a su familia pero deja la casa donde siempre ha estado por vivir donde se siente como nunca. No se agarra con el pueblo pero mantiene su pinta cuando cabalga por las calles y carreteras. Sigue creyendo en su virgencita pero la pone un poco vaquerita. En su <em>Western<\/em> entre las altas monta\u00f1as andinas no hay estrella del <em>sheriff<\/em>, pero s\u00ed corbat\u00edn chill\u00f3n que brilla.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Lo bello y lo dif\u00edcil <\/strong><\/p>\n<p>Esta puede ser una pel\u00edcula vaquera colombo-brit\u00e1nica. Y por supuesto que el efecto de las palabras hasta ahora escritas no se acerca mucho a la agradable sensaci\u00f3n de belleza que produce la pel\u00edcula al retratar esa vida y sus potencias colectivas. Una vida cuyos conflictos son escasos y con mucha fortuna. Desaf\u00eda con amabilidad y as\u00ed les responde el destino. Y quiz\u00e1s es as\u00ed para mostrar con optimismo la posibilidad de su consumaci\u00f3n. Aunque tal vez resulta demasiado f\u00e1cil\u2026 No obstante, la manera en que vive Bernicia es simple, no por ello f\u00e1cil. No conozco a nadie que viva as\u00ed. Podemos saber que poco de lo que vemos all\u00ed con Bernicia es gratuito, incluso si el mundo conspira a su favor, porque sin duda hay algo que resulta bello y genera placer verlo. Lo bello, por lo general, es dif\u00edcil. Y llevar esa vida, tanto tentada a ser dejada, no es cualquier cosa. Bernicia no se sacrifica. A la mayor\u00eda nos cuesta no tener que pagar un precio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Tamayo Uribe<\/p>\n","protected":false},"author":1,"featured_media":657,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-criticas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El vaquero, de Emma Rozanski - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El vaquero, de Emma Rozanski - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11\" \/>\n<meta property=\"og:description\" content=\"Daniel Tamayo Uribe\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/\" \/>\n<meta property=\"og:site_name\" content=\"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-05T02:18:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T01:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/canaguaro.cinefagos.net\/n11\/wp-content\/uploads\/sites\/14\/2024\/05\/CRITICAS-El-vaquero.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"856\" \/>\n\t<meta property=\"og:image:height\" content=\"482\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"headline\":\"El vaquero, de Emma Rozanski\",\"datePublished\":\"2024-05-05T02:18:32+00:00\",\"dateModified\":\"2024-07-12T01:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/\"},\"wordCount\":2349,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/05\\\/CRITICAS-El-vaquero.jpg\",\"articleSection\":[\"CRITICAS\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/\",\"name\":\"El vaquero, de Emma Rozanski - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/05\\\/CRITICAS-El-vaquero.jpg\",\"datePublished\":\"2024-05-05T02:18:32+00:00\",\"dateModified\":\"2024-07-12T01:30:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/el-vaquero-de-emma-rozanski\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/05\\\/CRITICAS-El-vaquero.jpg\",\"contentUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/wp-content\\\/uploads\\\/sites\\\/14\\\/2024\\\/05\\\/CRITICAS-El-vaquero.jpg\",\"width\":856,\"height\":482},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/#website\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/\",\"name\":\"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11\",\"description\":\"Revista de Cine Colombiano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/canaguaro.cinefagos.net\"],\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n11\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El vaquero, de Emma Rozanski - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/","og_locale":"en_US","og_type":"article","og_title":"El vaquero, de Emma Rozanski - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11","og_description":"Daniel Tamayo Uribe","og_url":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/","og_site_name":"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11","article_published_time":"2024-05-05T02:18:32+00:00","article_modified_time":"2024-07-12T01:30:00+00:00","og_image":[{"width":856,"height":482,"url":"http:\/\/canaguaro.cinefagos.net\/n11\/wp-content\/uploads\/sites\/14\/2024\/05\/CRITICAS-El-vaquero.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/#article","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/"},"author":{"name":"admin","@id":"https:\/\/canaguaro.cinefagos.net\/n11\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"headline":"El vaquero, de Emma Rozanski","datePublished":"2024-05-05T02:18:32+00:00","dateModified":"2024-07-12T01:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/"},"wordCount":2349,"commentCount":0,"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-content\/uploads\/sites\/14\/2024\/05\/CRITICAS-El-vaquero.jpg","articleSection":["CRITICAS"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/","url":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/","name":"El vaquero, de Emma Rozanski - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/#primaryimage"},"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-content\/uploads\/sites\/14\/2024\/05\/CRITICAS-El-vaquero.jpg","datePublished":"2024-05-05T02:18:32+00:00","dateModified":"2024-07-12T01:30:00+00:00","author":{"@id":"https:\/\/canaguaro.cinefagos.net\/n11\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/canaguaro.cinefagos.net\/n11\/el-vaquero-de-emma-rozanski\/#primaryimage","url":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-content\/uploads\/sites\/14\/2024\/05\/CRITICAS-El-vaquero.jpg","contentUrl":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-content\/uploads\/sites\/14\/2024\/05\/CRITICAS-El-vaquero.jpg","width":856,"height":482},{"@type":"WebSite","@id":"https:\/\/canaguaro.cinefagos.net\/n11\/#website","url":"https:\/\/canaguaro.cinefagos.net\/n11\/","name":"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 11","description":"Revista de Cine Colombiano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canaguaro.cinefagos.net\/n11\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/canaguaro.cinefagos.net\/n11\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/canaguaro.cinefagos.net"],"url":"https:\/\/canaguaro.cinefagos.net\/n11\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/posts\/568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/comments?post=568"}],"version-history":[{"count":3,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/posts\/568\/revisions"}],"predecessor-version":[{"id":572,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/posts\/568\/revisions\/572"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/media\/657"}],"wp:attachment":[{"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/media?parent=568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/categories?post=568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n11\/wp-json\/wp\/v2\/tags?post=568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}