{"id":797,"date":"2024-08-18T02:49:16","date_gmt":"2024-08-18T02:49:16","guid":{"rendered":"https:\/\/canaguaro.cinefagos.net\/n12\/?p=797"},"modified":"2024-08-18T02:49:16","modified_gmt":"2024-08-18T02:49:16","slug":"ella-de-jorge-pinto-1964","status":"publish","type":"post","link":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/","title":{"rendered":"Ella, de Jorge Pinto (1964)"},"content":{"rendered":"<p class=\"autor\">Santiago Nicol\u00e1s Giraldo Enr\u00edquez<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42 aligncenter\" src=\"https:\/\/canaguaro.cinefagos.net\/n05\/wp-content\/uploads\/sites\/7\/2021\/08\/sep.png\" alt=\"\" width=\"22\" height=\"8\" \/><\/p>\n<p class=\"entradilla\">Para la composici\u00f3n de eso que entendemos por cotidianidad (en principio pensada a nuestra merced), no somos m\u00e1s que un espectro ingr\u00e1vido y borroso. Las fibras que componen a los objetos nos miran, distantes, mientras tratan de identificarnos, de aceptarnos y de aceptarse. Los objetos que nos componen se escurren entre armarios, tocadores, ladrillos, ventanas y espejos; los conocemos tan bien que se nos hacen difusos, se escurren entre los recuerdos. Son tan nuestros que, igual que nuestras u\u00f1as, labios, miradas, poros y surcos, sus im\u00e1genes pierden nitidez dentro de esa nube de zumbidos que ocupa cada una de nuestras cabezas.<\/p>\n<p>&nbsp;<\/p>\n<p>Estos par\u00e1metros, vistos desde un punto de vista sensiblemente observacional y experimentalmente est\u00e9tico, movieron a un c\u00edrculo de artistas y pensadores, distintivos de su \u00e9poca y caracter\u00edsticos para la historia del cine (encabezados por Jorge Pinto), a realizar el cortometraje <em>Ella<\/em> (1964). En este, Gilda Mora \u2013artista visual\u2013 interpreta a una mujer de gestos p\u00e9treos que deambula una cotidianidad s\u00f3lida con pasos certeros, precisos. Observa y es observada en una din\u00e1mica que se rige por el inter\u00e9s hacia lo aparentemente nimio, que, en contraposici\u00f3n de una primera idea que se podr\u00eda tener acerca del concepto, supone aqu\u00ed una sustancia viva; llamativa por sus propios m\u00e9ritos.<\/p>\n<p>&nbsp;<\/p>\n<p>En un principio, y dentro de una habitaci\u00f3n hura\u00f1a que susurra su propia apariencia, los gestos circunspectos de esa mujer se dirigen \u2013a trav\u00e9s de los resquicios de una persiana entrecerrada y su ventana subsiguiente\u2013 hacia un exterior que apenas se dibuja como una enso\u00f1aci\u00f3n desva\u00edda. Sus ojos, enfatizados, se vuelven luego hacia ese espacio ya conocido, se posan en \u00e9l y lo acarician con displicencia. Una vez se mueven y observan a s\u00ed mismos, su percepci\u00f3n viaja hacia el otro lado de un espejo insondable que cambia su panorama sin virar sus m\u00e9todos.<\/p>\n<p>&nbsp;<\/p>\n<p>La instancia propuesta por el relato, a trav\u00e9s del uso del espejo, la mirada y los objetos, toma el gusto inmanente que suscitan esos rasgos dentro de un espacio (que, gracias a las decisiones creativas, nunca es el mismo) en el que esta mujer respira, para engrandecer lo observable y jugar con lo filmable. Con usos \u00f3pticos y lum\u00ednicos tan sutiles como categ\u00f3ricos, el cambio, como concepto, cae \u2013en una oscura y m\u00ednima noche que en lugar de cielo tiene pel\u00edcula y, a falta de estrellas, manchas\u2013 sobre el silencio de sus elementos.<\/p>\n<p>&nbsp;<\/p>\n<p>Tras este proceso, el cuerpo de Gilda Mora es pormenorizado y representado como un paisaje complejo, que, al moverse entre estatuas, se distingue de ellas. La cercan\u00eda entre la representaci\u00f3n de los objetos y el cuerpo femenino hila ambas ideas en una unicidad que hace respirar a los unos, y otorga un car\u00e1cter pl\u00e1stico al otro. Se acoplan en una conceptualizaci\u00f3n cinematogr\u00e1fica que concede rumbos art\u00edsticos propios a la aparente simpleza de su uni\u00f3n (en la que, con vistas a una trascendencia, no se funden ni comparan). Como resultado de esta captura f\u00edlmica, se llega a una concreci\u00f3n inusitada de las im\u00e1genes comunes que abrazan el trasegar diario, una concreci\u00f3n que se hace encantadoramente extra\u00f1a, atemporal y l\u00facida.<\/p>\n<blockquote class=\"destacado\"><p>La cercan\u00eda entre la representaci\u00f3n de los objetos y el cuerpo femenino hila ambas ideas en una unicidad que hace respirar a los unos, y otorga un car\u00e1cter pl\u00e1stico al otro.<\/p><\/blockquote>\n<p>En ambos lados de este espejo, entremezclados, la regularidad y sus posibles derivas \u2013que, aqu\u00ed al menos, son tan reales como ella y <em>Ella<\/em>\u2013 se iluminan y oscurecen la una a las otras, y las otras a la una, como una conversaci\u00f3n est\u00e9tica que permite una abstracci\u00f3n libre de adjudicaciones, juicios o adjetivos. La musicalidad presente en todo el metraje es, adem\u00e1s, una decisi\u00f3n cinematogr\u00e1fica seg\u00fan la cual la atenci\u00f3n se gu\u00eda directamente hacia las im\u00e1genes en pantalla, que son, a todas luces \u2013y sombras\u2013, quienes m\u00e1s expresan.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Ella<\/em> representa una forma de concebir el cine muy distinta a lo que, hasta ese momento, se hab\u00eda realizado en el pa\u00eds. Es un referente primigenio para aquellos cineastas que, a\u00f1os despu\u00e9s, explorar\u00edan diversas reflexiones no narrativas acerca del cine y la cotidianidad, as\u00ed como para aquellos con un inter\u00e9s especial por la representaci\u00f3n femenina \u2013en diferentes instancias\u2013, o la respiraci\u00f3n lenta y pesada (a la que a trav\u00e9s del cine se puede acceder) de seres y \u00e1mbitos est\u00e1ticos. Es un hito en la medida en que abri\u00f3 un camino nuevo para el pensamiento f\u00edlmico colombiano, y brind\u00f3 conceptos, hasta entonces in\u00e9ditos, para su emancipaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>En este momento, la figura de la mujer, en su cotidianidad y franqueza, est\u00e1 siendo representada por ellas mismas; los roles cinematogr\u00e1ficos van abri\u00e9ndose a toda clase de realizadores, y revisar producciones que, como est\u00e1, suponen alegatos aventurados a la profundidad de la esencia del g\u00e9nero, en un contexto tan problem\u00e1tico como el nuestro, vale no solo como un ejercicio de memoria, sino tambi\u00e9n de inspecci\u00f3n cr\u00edtica al pasado y sus paradigmas. La cinta toma un camino conceptual que transgrede los encasillamientos est\u00e9ticos de su tiempo, y es responsabilidad del nuestro tomarlo en cuenta como desembocadura creativa unificada a la sociedad.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Ver el cortometraje en: <\/strong><\/p>\n<p><a href=\"https:\/\/rtvcplay.co\/cortometrajes-ficcion\/ella\">https:\/\/rtvcplay.co\/cortometrajes-ficcion\/ella<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago Nicol\u00e1s Giraldo Enr\u00edquez<\/p>\n","protected":false},"author":1,"featured_media":798,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-797","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-retro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ella, de Jorge Pinto (1964) - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ella, de Jorge Pinto (1964) - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12\" \/>\n<meta property=\"og:description\" content=\"Santiago Nicol\u00e1s Giraldo Enr\u00edquez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/\" \/>\n<meta property=\"og:site_name\" content=\"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-18T02:49:16+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/canaguaro.cinefagos.net\/n12\/wp-content\/uploads\/sites\/15\/2024\/08\/SALA-RETRO-Ella-1964.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1129\" \/>\n\t<meta property=\"og:image:height\" content=\"603\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"headline\":\"Ella, de Jorge Pinto (1964)\",\"datePublished\":\"2024-08-18T02:49:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/\"},\"wordCount\":942,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2024\\\/08\\\/SALA-RETRO-Ella-1964.jpg\",\"articleSection\":[\"SALA RETRO\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/\",\"name\":\"Ella, de Jorge Pinto (1964) - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2024\\\/08\\\/SALA-RETRO-Ella-1964.jpg\",\"datePublished\":\"2024-08-18T02:49:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2024\\\/08\\\/SALA-RETRO-Ella-1964.jpg\",\"contentUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/wp-content\\\/uploads\\\/sites\\\/15\\\/2024\\\/08\\\/SALA-RETRO-Ella-1964.jpg\",\"width\":1129,\"height\":603},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/ella-de-jorge-pinto-1964\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ella, de Jorge Pinto (1964)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/#website\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/\",\"name\":\"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12\",\"description\":\"Revista de Cine Colombiano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"sameAs\":[\"http:\\\/\\\/canaguaro.cinefagos.net\"],\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n12\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ella, de Jorge Pinto (1964) - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/","og_locale":"en_US","og_type":"article","og_title":"Ella, de Jorge Pinto (1964) - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12","og_description":"Santiago Nicol\u00e1s Giraldo Enr\u00edquez","og_url":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/","og_site_name":"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12","article_published_time":"2024-08-18T02:49:16+00:00","og_image":[{"width":1129,"height":603,"url":"http:\/\/canaguaro.cinefagos.net\/n12\/wp-content\/uploads\/sites\/15\/2024\/08\/SALA-RETRO-Ella-1964.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#article","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/"},"author":{"name":"admin","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"headline":"Ella, de Jorge Pinto (1964)","datePublished":"2024-08-18T02:49:16+00:00","mainEntityOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/"},"wordCount":942,"commentCount":0,"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-content\/uploads\/sites\/15\/2024\/08\/SALA-RETRO-Ella-1964.jpg","articleSection":["SALA RETRO"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/","url":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/","name":"Ella, de Jorge Pinto (1964) - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#primaryimage"},"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-content\/uploads\/sites\/15\/2024\/08\/SALA-RETRO-Ella-1964.jpg","datePublished":"2024-08-18T02:49:16+00:00","author":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"breadcrumb":{"@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#primaryimage","url":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-content\/uploads\/sites\/15\/2024\/08\/SALA-RETRO-Ella-1964.jpg","contentUrl":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-content\/uploads\/sites\/15\/2024\/08\/SALA-RETRO-Ella-1964.jpg","width":1129,"height":603},{"@type":"BreadcrumbList","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/ella-de-jorge-pinto-1964\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canaguaro.cinefagos.net\/n12\/"},{"@type":"ListItem","position":2,"name":"Ella, de Jorge Pinto (1964)"}]},{"@type":"WebSite","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/#website","url":"https:\/\/canaguaro.cinefagos.net\/n12\/","name":"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 12","description":"Revista de Cine Colombiano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canaguaro.cinefagos.net\/n12\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/canaguaro.cinefagos.net\/n12\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6bfb5e7ea347ed86f579ece251577a81a1cffe3c7c84a4cbc01e5de982797880?s=96&d=mm&r=g","caption":"admin"},"sameAs":["http:\/\/canaguaro.cinefagos.net"],"url":"https:\/\/canaguaro.cinefagos.net\/n12\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/posts\/797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/comments?post=797"}],"version-history":[{"count":1,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/posts\/797\/revisions"}],"predecessor-version":[{"id":799,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/posts\/797\/revisions\/799"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/media\/798"}],"wp:attachment":[{"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/media?parent=797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/categories?post=797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n12\/wp-json\/wp\/v2\/tags?post=797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}