{"id":1305,"date":"2025-04-11T17:11:58","date_gmt":"2025-04-11T17:11:58","guid":{"rendered":"https:\/\/canaguaro.cinefagos.net\/n14\/?p=1305"},"modified":"2025-10-13T15:51:44","modified_gmt":"2025-10-13T15:51:44","slug":"1hijo1padre-de-andres-ramirez-pulido","status":"publish","type":"post","link":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/","title":{"rendered":"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido"},"content":{"rendered":"<p class=\"autor\">David Ocampo Hern\u00e1ndez<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-42 aligncenter\" src=\"https:\/\/canaguaro.cinefagos.net\/n05\/wp-content\/uploads\/sites\/7\/2021\/08\/sep.png\" alt=\"\" width=\"22\" height=\"8\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"entradilla\">Construir un universo cinematogr\u00e1fico en Colombia suena descabellado. Los \u00fanicos referentes <em>mainstream <\/em>que tenemos son las franquicias de superh\u00e9roes, muy distantes de los recursos y cosmogon\u00edas del cine que se produce en la regi\u00f3n. En medio de un cine colombiano que suele girar en torno a la violencia, la pobreza o el trauma social, Ram\u00edrez Pulido parece estar levantando otro camino. Uno m\u00e1s \u00edntimo, encerrado, s\u00ed, pero en lo afectivo: donde los personajes est\u00e1n acorralados por sus emociones, por sus v\u00ednculos, por los gestos que no saben nombrar. Sus pel\u00edculas no buscan explicar un pa\u00eds, sino explorar c\u00f3mo nos relacionamos, c\u00f3mo cargamos con el otro, incluso cuando no queremos.<\/p>\n<p>&nbsp;<\/p>\n<p>Su cine ha venido consolidando un universo particular desde <em>El Ed\u00e9n<\/em> (2016), pasando por <em>Damiana<\/em> (2017) y <em>La Jaur\u00eda<\/em> (2022), donde los espacios de reclusi\u00f3n \u2013institucionales, naturales, emocionales\u2013 se repiten como escenarios en los que se tensan las relaciones, se prueban los v\u00ednculos y se deja ver una humanidad tosca pero honesta.<\/p>\n<p>&nbsp;<\/p>\n<p><em>1 Hijo &amp; 1 Padre<\/em> (2025) mantiene la premisa de encerrar personajes en espacios que los confrontan, pero el tono se desplaza hacia la comedia. Aunque el entorno es menos opresivo, persiste esa tensi\u00f3n que atraviesa los v\u00ednculos masculinos: distantes, toscos, muchas veces mediadas por el sarcasmo y la burla como forma de afecto. Kevin, un joven problem\u00e1tico, es enviado por su colegio a un retiro obligatorio junto a su padre, con el fin de encontrarse consigo mismo y conectar con su progenitor. El padre biol\u00f3gico se niega a ir, por lo que es acompa\u00f1ado por don Andr\u00e9s, su padrastro, cuya figura escu\u00e1lida y t\u00edmida contrasta c\u00f3micamente con la complexi\u00f3n grande y fornida de Kevin.<\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed se genera un primer impacto c\u00f3mico que se desarrolla a medida que conocemos a las dem\u00e1s parejas de padres e hijos: un padre gordo y soez con su hijo flacuchento y aparentemente t\u00edmido; otros m\u00e1s parecidos, pero igual c\u00f3micos por los cr\u00edmenes de sus hijos \u2013hay hasta un traficante de drogas en ciernes dentro del grupo.<\/p>\n<p>&nbsp;<\/p>\n<p>El c\u00e1lido paisaje boscoso, junto con la fotograf\u00eda y el color cuidadosamente trabajados para construir la atm\u00f3sfera, nos va adentrando en la mirada de Kevin. \u00c9l hurga en las redes sociales de los dem\u00e1s asistentes al seminario, mientras tambi\u00e9n se ve a s\u00ed mismo en las fotos de sus familiares y de Andr\u00e9s. Tal vez no quiere aceptar que ahora este personaje sea su padre, lo ve m\u00e1s como un hermano, o como alguien inferior.<\/p>\n<blockquote class=\"destacado\"><p>El c\u00e1lido paisaje boscoso, junto con la fotograf\u00eda y el color cuidadosamente trabajados para construir la atm\u00f3sfera, nos va adentrando en la mirada de Kevin.<\/p><\/blockquote>\n<p>En un partido de baloncesto \u2013muestra del deporte como competencia por excelencia\u2013, Kevin y Andr\u00e9s se ven humillados por el padre gordo y su hijo. Esto detona en Kevin esa ira que guarda, acerc\u00e1ndonos lentamente, en un periodo de descanso, a esa mirada con la que sabemos que no se va a quedar callada.<\/p>\n<p>&nbsp;<\/p>\n<p>Un \u201cGordo triple hijueputa\u201d escrito en el tablero de baloncesto enciende el conflicto dentro del grupo. El otro padre quiere irse, no acepta la ofensa; mientras, cabizbajo y en calzoncillos, oculta su rabia. El seminarista (tambi\u00e9n de figura c\u00f3mica por sus gafas y su cuerpo delgado) lo convence de quedarse para la \u00faltima actividad: una caminata en pareja con su hijo, pensada para conectar en medio de la naturaleza.<\/p>\n<p>&nbsp;<\/p>\n<p>Ambas parejas de padre e hijo se pierden. Kevin y Andr\u00e9s, sentados, no quieren gastar el poco de agua que les queda. El otro padre llega al borde del infarto y les pide agua. Andr\u00e9s se compadece y se la da, el hombre la malgasta bebi\u00e9ndola y lav\u00e1ndose la cara. La tensi\u00f3n crece. \u00c9l anuncia que se va a devolver y les agradece. Silencio. Kevin mira con rabia a Andr\u00e9s: ya no tienen agua, y su padrastro se mostr\u00f3 d\u00e9bil ante el otro padre.<\/p>\n<p>&nbsp;<\/p>\n<p>De un momento a otro, un \u201cCon gusto, gordo triple hijueputa\u201d sale de la boca de Andr\u00e9s. Y junto con Kevin, se lanza a correr entre risas. Por fin han conectado de una manera familiar, evocando un paseo en charco con el resto de la familia: s\u00edmbolo de la uni\u00f3n que ahora sienten.<\/p>\n<p>&nbsp;<\/p>\n<p>El autor, entonces, nos deja conmovidos. Despu\u00e9s de varias risas, comprendemos que la familia se va encontrando cuando nos vemos reflejados en las acciones de los otros. Nos brinda otra perspectiva de este universo masculino que Ram\u00edrez Pulido ha venido trazando: un universo donde el afecto aparece entre la rabia, la torpeza y la risa, y donde los lazos m\u00e1s fuertes se construyen en los bordes difusos entre la burla y la lealtad.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>David Ocampo Hern\u00e1ndez<\/p>\n","protected":false},"author":1,"featured_media":1348,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-1305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sala-cortos"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14\" \/>\n<meta property=\"og:description\" content=\"David Ocampo Hern\u00e1ndez\" \/>\n<meta property=\"og:url\" content=\"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/\" \/>\n<meta property=\"og:site_name\" content=\"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-11T17:11:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-13T15:51:44+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/canaguaro.cinefagos.net\/n14\/wp-content\/uploads\/sites\/18\/2025\/04\/CRITICAS-Bienvenidos-conquistadores-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"headline\":\"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido\",\"datePublished\":\"2025-04-11T17:11:58+00:00\",\"dateModified\":\"2025-10-13T15:51:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/\"},\"wordCount\":842,\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2025\\\/04\\\/CRITICAS-Bienvenidos-conquistadores-3.jpg\",\"articleSection\":[\"SALA CORTOS\"],\"inLanguage\":\"es-CO\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/\",\"name\":\"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2025\\\/04\\\/CRITICAS-Bienvenidos-conquistadores-3.jpg\",\"datePublished\":\"2025-04-11T17:11:58+00:00\",\"dateModified\":\"2025-10-13T15:51:44+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#primaryimage\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2025\\\/04\\\/CRITICAS-Bienvenidos-conquistadores-3.jpg\",\"contentUrl\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/wp-content\\\/uploads\\\/sites\\\/18\\\/2025\\\/04\\\/CRITICAS-Bienvenidos-conquistadores-3.jpg\",\"width\":1280,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/1hijo1padre-de-andres-ramirez-pulido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/#website\",\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/\",\"name\":\"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14\",\"description\":\"Revista de Cine Colombiano\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/#\\\/schema\\\/person\\\/e08bd89ff0fc2cab36e00254c8fe7c30\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/canaguaro.cinefagos.net\"],\"url\":\"https:\\\/\\\/canaguaro.cinefagos.net\\\/n14\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/","og_locale":"es_ES","og_type":"article","og_title":"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14","og_description":"David Ocampo Hern\u00e1ndez","og_url":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/","og_site_name":"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14","article_published_time":"2025-04-11T17:11:58+00:00","article_modified_time":"2025-10-13T15:51:44+00:00","og_image":[{"width":1280,"height":720,"url":"http:\/\/canaguaro.cinefagos.net\/n14\/wp-content\/uploads\/sites\/18\/2025\/04\/CRITICAS-Bienvenidos-conquistadores-3.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#article","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/"},"author":{"name":"admin","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"headline":"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido","datePublished":"2025-04-11T17:11:58+00:00","dateModified":"2025-10-13T15:51:44+00:00","mainEntityOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/"},"wordCount":842,"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-content\/uploads\/sites\/18\/2025\/04\/CRITICAS-Bienvenidos-conquistadores-3.jpg","articleSection":["SALA CORTOS"],"inLanguage":"es-CO"},{"@type":"WebPage","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/","url":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/","name":"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido - CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14","isPartOf":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/#website"},"primaryImageOfPage":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#primaryimage"},"image":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#primaryimage"},"thumbnailUrl":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-content\/uploads\/sites\/18\/2025\/04\/CRITICAS-Bienvenidos-conquistadores-3.jpg","datePublished":"2025-04-11T17:11:58+00:00","dateModified":"2025-10-13T15:51:44+00:00","author":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30"},"breadcrumb":{"@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#primaryimage","url":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-content\/uploads\/sites\/18\/2025\/04\/CRITICAS-Bienvenidos-conquistadores-3.jpg","contentUrl":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-content\/uploads\/sites\/18\/2025\/04\/CRITICAS-Bienvenidos-conquistadores-3.jpg","width":1280,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/1hijo1padre-de-andres-ramirez-pulido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/canaguaro.cinefagos.net\/n14\/"},{"@type":"ListItem","position":2,"name":"1 Hijo &amp; 1 Padre, de Andr\u00e9s Ram\u00edrez Pulido"}]},{"@type":"WebSite","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/#website","url":"https:\/\/canaguaro.cinefagos.net\/n14\/","name":"CANAGUARO - Revista de cine colombiano - Edici\u00f3n 14","description":"Revista de Cine Colombiano","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/canaguaro.cinefagos.net\/n14\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"},{"@type":"Person","@id":"https:\/\/canaguaro.cinefagos.net\/n14\/#\/schema\/person\/e08bd89ff0fc2cab36e00254c8fe7c30","name":"admin","sameAs":["http:\/\/canaguaro.cinefagos.net"],"url":"https:\/\/canaguaro.cinefagos.net\/n14\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/posts\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/comments?post=1305"}],"version-history":[{"count":9,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/posts\/1305\/revisions"}],"predecessor-version":[{"id":1440,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/posts\/1305\/revisions\/1440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/media\/1348"}],"wp:attachment":[{"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/media?parent=1305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/categories?post=1305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/canaguaro.cinefagos.net\/n14\/wp-json\/wp\/v2\/tags?post=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}